{"id":174,"date":"2020-05-12T13:42:12","date_gmt":"2020-05-12T13:42:12","guid":{"rendered":"https:\/\/bridge363.qodeinteractive.com\/?page_id=174"},"modified":"2026-04-24T16:07:24","modified_gmt":"2026-04-24T19:07:24","slug":"sobre","status":"publish","type":"page","link":"https:\/\/weplayacademia.com.br\/index.php\/sobre\/","title":{"rendered":"Sobre a WePlay"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"174\" class=\"elementor elementor-174\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-67d4e98a elementor-section-full_width qode-row-background elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"67d4e98a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5f2b4fee\" data-id=\"5f2b4fee\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-153ccffc elementor-section-full_width qode_elementor_container_inner elementor-section-height-default elementor-section-height-default parallax_section_no\" data-id=\"153ccffc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-446cc1f0\" data-id=\"446cc1f0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f749cb5 elementor-widget elementor-widget-text-editor\" data-id=\"f749cb5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h1 style=\"text-align: center;\">Sobre a WePlay<\/h1>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-751bd8cb elementor-section-full_width qode_elementor_container_inner elementor-section-height-default elementor-section-height-default parallax_section_no\" data-id=\"751bd8cb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-231c6730\" data-id=\"231c6730\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-61e2e0d elementor-widget elementor-widget-video\" data-id=\"61e2e0d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;video_type&quot;:&quot;hosted&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t\t\t\t<div class=\"e-hosted-video elementor-wrapper elementor-open-inline\">\n\t\t\t\t\t<video class=\"elementor-video\" src=\"https:\/\/weplayacademia.com.br\/wp-content\/uploads\/2026\/04\/Copia-de-20210515-We-Play-Academia-Tour-v1.2.mp4\" controls=\"\" preload=\"metadata\" controlsList=\"nodownload\" poster=\"https:\/\/weplayacademia.com.br\/wp-content\/uploads\/2026\/04\/12.png\"><\/video>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e5ef286 elementor-section-full_width qode_elementor_container_inner elementor-section-height-default elementor-section-height-default parallax_section_no\" data-id=\"e5ef286\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-ad40762\" data-id=\"ad40762\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-11500cf elementor-widget elementor-widget-text-editor\" data-id=\"11500cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h5>Quem somos<\/h5>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a48a855 elementor-widget elementor-widget-text-editor\" data-id=\"a48a855\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h2><strong>Nossa hist\u00f3ria come\u00e7a com movimento.<\/strong><\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-d486d13\" data-id=\"d486d13\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-66365b4 elementor-section-full_width elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"66365b4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-e963b01\" data-id=\"e963b01\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7c8c281 elementor-widget elementor-widget-text-editor\" data-id=\"7c8c281\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">A We Play nasceu em Curitiba em 2012 com um prop\u00f3sito claro: usar o movimento como ferramenta de sa\u00fade, bem-estar e longevidade para pessoas reais, com rotinas reais. Desde ent\u00e3o, seguimos evoluindo com duas unidades \u2014 no \u00c1gua Verde e no Batel \u2014, oferecendo uma estrutura completa de muscula\u00e7\u00e3o, Pilates, Spinning, funcional e aulas coletivas, sempre com acompanhamento profissional.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-43203c0 elementor-section-full_width qode_elementor_container_inner elementor-section-height-default elementor-section-height-default parallax_section_no\" data-id=\"43203c0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-08ba357\" data-id=\"08ba357\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1605756 elementor-widget elementor-widget-image\" data-id=\"1605756\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1920\" height=\"1282\" src=\"https:\/\/weplayacademia.com.br\/wp-content\/uploads\/2026\/04\/15.png\" class=\"attachment-full size-full wp-image-595\" alt=\"\" srcset=\"https:\/\/weplayacademia.com.br\/wp-content\/uploads\/2026\/04\/15.png 1920w, https:\/\/weplayacademia.com.br\/wp-content\/uploads\/2026\/04\/15-300x200.png 300w, https:\/\/weplayacademia.com.br\/wp-content\/uploads\/2026\/04\/15-1024x684.png 1024w, https:\/\/weplayacademia.com.br\/wp-content\/uploads\/2026\/04\/15-768x513.png 768w, https:\/\/weplayacademia.com.br\/wp-content\/uploads\/2026\/04\/15-1536x1026.png 1536w, https:\/\/weplayacademia.com.br\/wp-content\/uploads\/2026\/04\/15-700x467.png 700w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-450f174 elementor-widget elementor-widget-text-editor\" data-id=\"450f174\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h4 style=\"text-align: center;\"><strong>Sa\u00fade al\u00e9m da est\u00e9tica.<\/strong><b><\/b><\/h4>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fe9dbc7 elementor-widget elementor-widget-text-editor\" data-id=\"fe9dbc7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">Na <strong>WePlay<\/strong>, sa\u00fade n\u00e3o \u00e9 um projeto de ver\u00e3o. \u00c9 um projeto de vida. Acreditamos que a atividade f\u00edsica transforma o corpo, mas tamb\u00e9m impacta diretamente o humor, o sono, a energia, a autonomia e a preven\u00e7\u00e3o de doen\u00e7as cr\u00f4nicas. Por isso, todo o nosso discurso e nossas pr\u00e1ticas est\u00e3o voltados para ajudar voc\u00ea a viver melhor hoje e a chegar ao futuro com mais liberdade, for\u00e7a e independ\u00eancia.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-db3dc7b\" data-id=\"db3dc7b\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ed14f0f elementor-widget elementor-widget-image\" data-id=\"ed14f0f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1920\" height=\"1282\" src=\"https:\/\/weplayacademia.com.br\/wp-content\/uploads\/2026\/04\/16.png\" class=\"attachment-full size-full wp-image-596\" alt=\"\" srcset=\"https:\/\/weplayacademia.com.br\/wp-content\/uploads\/2026\/04\/16.png 1920w, https:\/\/weplayacademia.com.br\/wp-content\/uploads\/2026\/04\/16-300x200.png 300w, https:\/\/weplayacademia.com.br\/wp-content\/uploads\/2026\/04\/16-1024x684.png 1024w, https:\/\/weplayacademia.com.br\/wp-content\/uploads\/2026\/04\/16-768x513.png 768w, https:\/\/weplayacademia.com.br\/wp-content\/uploads\/2026\/04\/16-1536x1026.png 1536w, https:\/\/weplayacademia.com.br\/wp-content\/uploads\/2026\/04\/16-700x467.png 700w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f2ce621 elementor-widget elementor-widget-text-editor\" data-id=\"f2ce621\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h4 style=\"text-align: center;\"><strong>O que guia nossos treinos: ci\u00eancia e cuidado.<\/strong><\/h4>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-88c8390 elementor-widget elementor-widget-text-editor\" data-id=\"88c8390\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">Nossa equipe passa por atualiza\u00e7\u00f5es constantes, participando de palestras e forma\u00e7\u00f5es sobre temas como prescri\u00e7\u00e3o de treino para pessoas idosas e impacto da atividade f\u00edsica em condi\u00e7\u00f5es como obesidade, c\u00e2ncer, TEA e doen\u00e7as cr\u00f4nicas. Isso significa que, por tr\u00e1s de cada ficha de treino, existe estudo, intencionalidade e respeito \u00e0s particularidades de cada corpo.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-61dbaea\" data-id=\"61dbaea\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a2099b1 elementor-widget elementor-widget-image\" data-id=\"a2099b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1920\" height=\"1282\" src=\"https:\/\/weplayacademia.com.br\/wp-content\/uploads\/2026\/04\/17.png\" class=\"attachment-full size-full wp-image-597\" alt=\"\" srcset=\"https:\/\/weplayacademia.com.br\/wp-content\/uploads\/2026\/04\/17.png 1920w, https:\/\/weplayacademia.com.br\/wp-content\/uploads\/2026\/04\/17-300x200.png 300w, https:\/\/weplayacademia.com.br\/wp-content\/uploads\/2026\/04\/17-1024x684.png 1024w, https:\/\/weplayacademia.com.br\/wp-content\/uploads\/2026\/04\/17-768x513.png 768w, https:\/\/weplayacademia.com.br\/wp-content\/uploads\/2026\/04\/17-1536x1026.png 1536w, https:\/\/weplayacademia.com.br\/wp-content\/uploads\/2026\/04\/17-700x467.png 700w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d4efc59 elementor-widget elementor-widget-text-editor\" data-id=\"d4efc59\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h4 style=\"text-align: center;\"><strong>Treino \u00e9 importante. Relacionamento tamb\u00e9m.<\/strong><\/h4>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-97aff17 elementor-widget elementor-widget-text-editor\" data-id=\"97aff17\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">Mais do que m\u00e1quinas e aulas, acreditamos em gente cuidando de gente. Cada aluno tem uma hist\u00f3ria, um ritmo e um contexto \u2014 e isso \u00e9 levado em conta no dia a dia. O relacionamento pr\u00f3ximo entre professores e alunos, o clima acolhedor e o cuidado com o ambiente fazem parte do que sustenta a experi\u00eancia <strong>WePlay<\/strong>.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ff13408 elementor-section-full_width qode_elementor_container_inner elementor-section-height-default elementor-section-height-default parallax_section_no\" data-id=\"ff13408\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-94f7abd\" data-id=\"94f7abd\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5bb5c56 elementor-widget elementor-widget-image\" data-id=\"5bb5c56\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1920\" height=\"1282\" src=\"https:\/\/weplayacademia.com.br\/wp-content\/uploads\/2026\/04\/15.png\" class=\"attachment-full size-full wp-image-595\" alt=\"\" srcset=\"https:\/\/weplayacademia.com.br\/wp-content\/uploads\/2026\/04\/15.png 1920w, https:\/\/weplayacademia.com.br\/wp-content\/uploads\/2026\/04\/15-300x200.png 300w, https:\/\/weplayacademia.com.br\/wp-content\/uploads\/2026\/04\/15-1024x684.png 1024w, https:\/\/weplayacademia.com.br\/wp-content\/uploads\/2026\/04\/15-768x513.png 768w, https:\/\/weplayacademia.com.br\/wp-content\/uploads\/2026\/04\/15-1536x1026.png 1536w, https:\/\/weplayacademia.com.br\/wp-content\/uploads\/2026\/04\/15-700x467.png 700w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-abe2ece\" data-id=\"abe2ece\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f9282c6 elementor-widget elementor-widget-text-editor\" data-id=\"f9282c6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h4 style=\"text-align: center;\"><span style=\"color: #752995;\"><strong>Uma trajet\u00f3ria constru\u00edda dia ap\u00f3s dia.<\/strong><\/span><\/h4>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a12e4cd elementor-widget elementor-widget-text-editor\" data-id=\"a12e4cd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">Desde a abertura da primeira unidade em Curitiba, em 2012, a hist\u00f3ria da <strong>WePlay<\/strong> \u00e9 feita de escolhas di\u00e1rias: investir em estrutura, ampliar modalidades, fortalecer a equipe e manter o foco na sa\u00fade como prioridade. Cada aluno que entra para a nossa comunidade ajuda a escrever os pr\u00f3ximos cap\u00edtulos dessa jornada.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-24898b7e elementor-section-full_width qode_elementor_container_inner elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-height-default elementor-section-height-default parallax_section_no\" data-id=\"24898b7e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-792d17b2\" data-id=\"792d17b2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-71635c1d elementor-widget elementor-widget-text-editor\" data-id=\"71635c1d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h5 style=\"text-align: center;\">Testimonials<\/h5>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-31bc1793 elementor-widget elementor-widget-text-editor\" data-id=\"31bc1793\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h2 style=\"text-align: center;\">clients say<\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-74a1f755 elementor-widget elementor-widget-bridge_testimonials_carousel\" data-id=\"74a1f755\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"bridge_testimonials_carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class='testimonials_c_holder clearfix '><div class=\"testimonials_c testimonials_c_carousel\" data-show-navigation=\"\" data-animation-speed=\"500\" data-auto-rotate-slides=\"3\" data-number-per-slide=\"1\"><ul class=\"slides\"><li id=\"testimonials-c-41\" class=\"testimonial_content\"><div class=\"testimonial_content_inner\"><div class=\"testimonial_text_holder\"><div class=\"testimonial_text_inner\" style=\"\"><p >Mnesarchum temporibus definitionem ex nam, vix at posse principes corrumpit. Ad etiam epicurei oporteat mel. Vis ubique noster moderatius ex, te eos cetero aliquip, brute fabulas vituperatoribus vis ex. Pri eius epicurei consequuntur et.<\/p><p class=\"testimonial_author\" style=\"\">Twyla Lederman<\/p><\/div><\/div><\/div><\/li><li id=\"testimonials-c-40\" class=\"testimonial_content\"><div class=\"testimonial_content_inner\"><div class=\"testimonial_text_holder\"><div class=\"testimonial_text_inner\" style=\"\"><p >Te has diam aliquam repudiare, mei lorem recusabo forensibus id. Cu eos modus iusto diceret, vim enim mollis in. An mea liber persius ponderum, vel id exerci eloquentiam, sed idque impedit oporteat in. Mei ea vocibus dissentiet.<\/p><p class=\"testimonial_author\" style=\"\">David Clement<\/p><\/div><\/div><\/div><\/li><li id=\"testimonials-c-39\" class=\"testimonial_content\"><div class=\"testimonial_content_inner\"><div class=\"testimonial_text_holder\"><div class=\"testimonial_text_inner\" style=\"\"><p >Lorem ipsum dolor sit amet, moderatius complectitur has in, putent volumus voluptatum mel ad, ut vix facer assum percipitur. Cu his sonet nobis verear, ut nisl saperet sit, mea scaevola vivendum ea. Ad quaestio vulputate mea.<\/p><p class=\"testimonial_author\" style=\"\">Clara Spader<\/p><\/div><\/div><\/div><\/li><\/ul><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-18ad9d46 elementor-section-full_width elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"18ad9d46\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d16ddda\" data-id=\"d16ddda\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-82834ad elementor-section-full_width qode_elementor_container_inner elementor-section-height-default elementor-section-height-default parallax_section_no\" data-id=\"82834ad\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-inner-column elementor-element elementor-element-e34612a\" data-id=\"e34612a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-38f0bdd elementor-widget elementor-widget-text-editor\" data-id=\"38f0bdd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h3><span style=\"color: #080808;\">Subscribe to newsletter!<\/span><\/h3>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-37ddb4a\" data-id=\"37ddb4a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-08514ec elementor-widget elementor-widget-bridge_cf_7\" data-id=\"08514ec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"bridge_cf_7.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t    <div class=\"qode-contact-form-7 qode-contact-form-7-0\">\n    \n<div class=\"wpcf7 no-js\" id=\"wpcf7-f211-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"211\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/index.php\/wp-json\/wp\/v2\/pages\/174#wpcf7-f211-o1\" method=\"post\" class=\"wpcf7-form init cf7_custom_style_1\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"211\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f211-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class=\"qode-cf-newsletter-outer\">\n<div class=\"qode-cf-newsletter-mail\"><span class=\"wpcf7-form-control-wrap\" data-name=\"email-978\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-text wpcf7-validates-as-email\" aria-invalid=\"false\" placeholder=\"Enter E-Mail\" value=\"\" type=\"email\" name=\"email-978\" \/><\/span><\/div>\n<div class=\"qode-cf-newsletter-submit\"><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"&#xf064;\" \/><\/div>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n    <\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Sobre a WePlay https:\/\/weplayacademia.com.br\/wp-content\/uploads\/2026\/04\/Copia-de-20210515-We-Play-Academia-Tour-v1.2.mp4 Quem somos Nossa hist\u00f3ria come\u00e7a com movimento. A We Play nasceu em Curitiba em 2012 com um prop\u00f3sito claro: usar o movimento como ferramenta de sa\u00fade, bem-estar e longevidade para pessoas reais, com rotinas reais. Desde ent\u00e3o, seguimos evoluindo com duas&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"full_width.php","meta":{"footnotes":""},"class_list":["post-174","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/weplayacademia.com.br\/index.php\/wp-json\/wp\/v2\/pages\/174","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/weplayacademia.com.br\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/weplayacademia.com.br\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/weplayacademia.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/weplayacademia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=174"}],"version-history":[{"count":7,"href":"https:\/\/weplayacademia.com.br\/index.php\/wp-json\/wp\/v2\/pages\/174\/revisions"}],"predecessor-version":[{"id":625,"href":"https:\/\/weplayacademia.com.br\/index.php\/wp-json\/wp\/v2\/pages\/174\/revisions\/625"}],"wp:attachment":[{"href":"https:\/\/weplayacademia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=174"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}